{"id":911,"date":"2019-10-17T16:10:39","date_gmt":"2019-10-17T14:10:39","guid":{"rendered":"http:\/\/implantologie-rabat.com\/?p=911"},"modified":"2019-10-17T17:40:54","modified_gmt":"2019-10-17T15:40:54","slug":"vrai-faux-10-idees-recues-sur-les-implants-dentaires","status":"publish","type":"post","link":"https:\/\/implantologie-rabat.com\/index.php\/2019\/10\/17\/vrai-faux-10-idees-recues-sur-les-implants-dentaires\/","title":{"rendered":"Vrai \/ Faux : 10 id\u00e9es re\u00e7ues sur les implants dentaires"},"content":{"rendered":"<h3>La pose d&rsquo;un implant dentaire est douloureuse, le corps peut rejeter un implant en titane, une proth\u00e8se dentaire est toujours plus fragile qu&rsquo;une dent d&rsquo;origine\u2026 On fait le point sur les id\u00e9es re\u00e7ues concernant ce dispositif m\u00e9dical.<\/h3>\n<h3>La pose d&rsquo;un implant dentaire est douloureuse<br \/>\nFAUX.<\/h3>\n<p>La pose d\u2019un\u00a0implant dentaire, lorsqu\u2019elle est bien men\u00e9e, entraine moins de\u00a0douleurs\u00a0et de gonflements qu\u2019une extraction dentaire simple par exemple. L&rsquo;intervention est quasiment toujours couverte par des\u00a0antibiotiques\u00a0antalgiques et des anti-inflammatoires.<br \/>\nLes suites sont mineures dans l\u2019immense majorit\u00e9 des cas. Elles peuvent s\u2019alourdir un peu en cas de reconstruction osseuse ou gingivale associ\u00e9e.<\/p>\n<h3>Plusieurs s\u00e9ances sont n\u00e9cessaires pour la pose d&rsquo;un implant dentaire<br \/>\nVRAI.<\/h3>\n<p>Il faut bien distinguer deux aspects du traitement implantaire : le placement de l\u2019implant dentaire lui-m\u00eame d\u2019une part, et la connexion \u00e0 cet implant de la proth\u00e8se\u00a0\u00ab\u00a0implanto-port\u00e9e\u00a0\u00bb\u00a0d&rsquo;autre part. L\u2019implant en lui-m\u00eame est une vis de titane faisant office de racine artificielle. Seule, cette vis est inutile au patient, et ne devient utile que lorsque la proth\u00e8se (couronne ou\u00a0bridge, selon les cas) y est connect\u00e9e. Le couple implant \u2013 proth\u00e8se remplit alors son r\u00f4le masticatoire et esth\u00e9tique.<\/p>\n<p>De fait, il faut donc au moins deux s\u00e9ances pour remplacer totalement une dent par un implant : une s\u00e9ance chirurgicale (pose de la vis) et une s\u00e9ance proth\u00e9tique.<\/p>\n<p>Par ailleurs, l\u2019os et la gencive sur le site devant recevoir l\u2019implant ne sont pas toujours suffisants en quantit\u00e9 et\/ou en qualit\u00e9, il peut alors \u00eatre n\u00e9cessaire de reconstruire l\u2019os et\/ou la gencive avant le placement de l\u2019implant, ce qui augmente le nombre des s\u00e9ances n\u00e9cessaires.<\/p>\n<h3>Le corps peut rejeter l&rsquo;implant<br \/>\nFAUX, mais\u2026<\/h3>\n<p>Lorsqu\u2019un implant ne tient pas dans la m\u00e2choire, ce n\u2019est jamais par un ph\u00e9nom\u00e8ne de rejet au sens m\u00e9dical du terme en fait. Cela n\u2019a rien \u00e0 voir avec les r\u00e9actions immunologiques de rejet observ\u00e9es dans le cas des greffes d\u2019organes (peau, rein\u2026). En clair, ce n\u2019est pas l\u2019organisme du patient qui rejette un corps \u00e9tranger.<\/p>\n<p>En implantologie, on parlera donc d\u2019\u00e9chec implantaire et pas de rejet. Le ph\u00e9nom\u00e8ne d\u2019ost\u00e9o-int\u00e9gration, ph\u00e9nom\u00e8ne biologique qui se solde par l\u2019ancrage de l\u2019implant \u00e0 la m\u00e2choire, peut dysfonctionner pour diff\u00e9rentes raisons : m\u00e9caniques ou infectieuses principalement, mais ce n\u2019est jamais un rejet de principe du corps.<\/p>\n<h3>On ne peut pas faire poser plusieurs implants en m\u00eame temps<br \/>\nFAUX.<\/h3>\n<p>Au contraire, c\u2019est pr\u00e9f\u00e9rable, cela \u00e9vite de subir plusieurs interventions chirurgicales, ce qui implique moins de temps consacr\u00e9 aux soins, moins d\u2019anxi\u00e9t\u00e9, moins de p\u00e9nibilit\u00e9, moins de\u00a0m\u00e9dicaments\u2026<\/p>\n<p>Lorsque la situation clinique le permet, il est souhaitable de r\u00e9aliser le plus possible de soins chirurgicaux en une s\u00e9ance (reconstructions osseuse ou gingivale, placement de plusieurs implants\u2026).<\/p>\n<p>Pour les longues s\u00e9ances de traitement, la s\u00e9dation consciente permet d\u2019\u00eatre plac\u00e9 dans un \u00e9tat de relaxation, voir de quasi-sommeil, propice \u00e0 ce que de longs soins se d\u00e9roulent id\u00e9alement sans stress ni impatience. L\u2019anesth\u00e9sie fait disparaitre la douleur, mais n\u2019a pas d\u2019effet sur l\u2019esprit, c\u2019est pourquoi des protocoles de s\u00e9dation ont \u00e9t\u00e9 d\u00e9velopp\u00e9s.<\/p>\n<h3>Un implant dentaire co\u00fbte tr\u00e8s cher<br \/>\nVRAI et FAUX.<\/h3>\n<p>\u00c7a d\u00e9pend. Le cout li\u00e9 au placement d\u2019un implant dentaire est li\u00e9 \u00e0 la complexit\u00e9 de la situation clinique, aux exigences en termes de confort ou d\u2019esth\u00e9tique des patients, au plateau technique mis \u00e0 disposition, \u00e0 la marque d\u2019implant dentaire utilis\u00e9e, \u00e0 l\u2019expertise des intervenants\u2026<\/p>\n<p>Les implants ne sont pas pris en charge par la s\u00e9curit\u00e9 sociale et rarement par les mutuelles. Ils ne sont pas n\u00e9cessairement chers en soit compar\u00e9s \u00e0 d\u2019autres soins, mais sont certainement plus impactant dans un budget \u00e0 cause de leur absence de prise en charge.<\/p>\n<h3>Un implant dentaire se voit, il est diff\u00e9rent des dents d&rsquo;origine<br \/>\nVRAI et FAUX.<\/h3>\n<p>Du point de vue confort de mastication d\u2019abord, il n\u2019y a aucune diff\u00e9rence perceptible entre une dent naturelle et un implant, si bien que tr\u00e8s vite le porteur oublie quelle dent est \u00e0 lui et quelle dent est reconstruite par un implant. L&rsquo;implant n&rsquo;est pas plus fragile et il est possible de manger de tout.<br \/>\nDu point de vue esth\u00e9tique, maintenant, cela d\u00e9pend de plusieurs facteurs : de la complexit\u00e9 de la situation clinique de d\u00e9part, mais aussi de l\u2019expertise des intervenants. Lorsque toutes les conditions id\u00e9ales sont r\u00e9unies, il peut n\u2019y avoir aucune diff\u00e9rence esth\u00e9tique entre un implant dentaire et une dent naturelle.<\/p>\n<h3>On ne peut pas avoir de carie sur un implant dentaire<br \/>\nVRAI, mais\u2026<\/h3>\n<p>L\u2019implant est en titane, et la proth\u00e8se est soit totalement en c\u00e9ramique, soit c\u00e9ramo-m\u00e9tallique. Aucun de ces mat\u00e9riaux n\u2019est sensible aux bact\u00e9ries qui provoquent les caries. Un implant ne sera donc jamais attaqu\u00e9 par la\u00a0carie\u00a0dentaire.<\/p>\n<p>En revanche les tissus p\u00e9ri-implantaires, c\u2019est-\u00e0-dire la gencive et l\u2019os, qui assurent l\u2019ancrage de l\u2019implant dans la m\u00e2choire, sont eux tr\u00e8s sensibles aux bact\u00e9ries : si trop de\u00a0bact\u00e9ries\u00a0s\u2019accumulent \u00e0 proximit\u00e9 d\u2019un implant, une maladie grave pour l\u2019implant peut apparaitre et entrainer son expulsion. Cette maladie s\u2019appelle la p\u00e9ri-implantite. Tr\u00e8s rarement douloureuse sauf \u00e0 un stade avanc\u00e9, cette maladie est rarement perceptible par le patient lui-m\u00eame, et doit faire l\u2019objet d\u2019un d\u00e9pistage r\u00e9gulier.<\/p>\n<h3>On ne peut pas blanchir un implant dentaire<br \/>\nVRAI, mais\u2026<\/h3>\n<p>La proth\u00e8se port\u00e9e par l\u2019implant dentaire n\u2019est pas sensible aux produits utilis\u00e9s pour le\u00a0blanchiment des dents, sa teinte est invariable. En revanche, apr\u00e8s blanchiment des\u00a0dents\u00a0naturelles, la proth\u00e8se port\u00e9e par l\u2019implant peut \u00eatre chang\u00e9e et remplac\u00e9e par une nouvelle proth\u00e8se avec une teinte \u00e9claircie tout en conservant le m\u00eame implant.<\/p>\n<h3>On peut sonner aux portiques de s\u00e9curit\u00e9 \u00e0 cause du titane<br \/>\nFAUX.<\/h3>\n<p>Les portiques de s\u00e9curit\u00e9 des a\u00e9roports sont r\u00e9gl\u00e9s pour d\u00e9pister certains mat\u00e9riaux avec certains seuils. Pour des raisons de s\u00e9curit\u00e9, l\u2019industrie est assez discr\u00e8te sur les d\u00e9tails. En tous cas, les dispositifs implantaires passent sous le seuil de d\u00e9tection et ne vous occasionneront aucun tracas.<\/p>\n<h3>Un implant dentaire c&rsquo;est pour la vie<br \/>\nVRAI, mais\u2026<\/h3>\n<p>En th\u00e9orie oui, en pratique cela d\u00e9pend. Comme pour tout dispositif m\u00e9dical, il peut y avoir des complications, principalement m\u00e9caniques ou infectieuses ; c\u2019est pourquoi des pr\u00e9cautions doivent \u00eatre prises :<br \/>\n&#8211; Leur placement doit r\u00e9pondre \u00e0 un protocole tr\u00e8s rigoureux<br \/>\n&#8211; Les patients porteurs d\u2019implant(s) doivent avoir un suivi annuel ou biannuel selon les cas pour intercepter pr\u00e9cocement toute complication.<br \/>\nPatient et praticien ont donc tous les deux une responsabilit\u00e9 dans le bon comportement \u00e0 long terme d\u2019un implant.<\/p>\n<h3>Implant dentaire : quel entretien ?<\/h3>\n<p>Entretenir correctement son implant dentaire, c&rsquo;est indispensable : plus on prend soin de l&rsquo;implant, plus sa dur\u00e9e de vie est longue ! En outre, les patients qui b\u00e9n\u00e9ficient d&rsquo;un implant dentaire sont g\u00e9n\u00e9ralement des patients \u00ab\u00a0\u00e0 risque\u00a0\u00bb pour les maladies carieuses, gingivales ou encore parodontales. Pas question, donc, de rel\u00e2cher sa vigilance !<\/p>\n<ul>\n<li>Le\u00a0brossage des dents\u00a0(et de l&rsquo;implant !) est primordial : il doit avoir lieu (au moins) 2 fois par jour pendant 3 minutes, de la gencive vers la dent.\u00a0Attention :\u00a0il faut attendre 3 mois avant de reprendre l&rsquo;utilisation d&rsquo;une brosse \u00e0 dents \u00e9lectrique apr\u00e8s la pose d&rsquo;un implant dentaire.<\/li>\n<li>Pour compl\u00e9ter le brossage, on doit utiliser 1 fois par jour une brossette interdentaire (ou un\u00a0fil dentaire) pour atteindre les zones entre les dents (ou entre les implants) et retirer les d\u00e9p\u00f4ts qui sont \u00e0 l\u2019origine de la formation de la plaque dentaire.\u00a0Bon \u00e0 savoir :\u00a0il existe (en pharmacie) des fils dentaires d\u00e9di\u00e9s \u00e0 l&rsquo;entretien des implants &#8211; notamment en cas de bridge.<\/li>\n<li>\u00c9videmment, il est n\u00e9cessaire de prendre r\u00e9guli\u00e8rement rendez-vous chez son dentiste pour le suivi post-op\u00e9ratoire et la surveillance de l&rsquo;implant.<\/li>\n<\/ul>\n<p>Source : femmeactuelle.fr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pose d&rsquo;un implant dentaire est douloureuse, le corps peut rejeter un implant en titane, une proth\u00e8se dentaire est toujours plus fragile qu&rsquo;une dent d&rsquo;origine\u2026 On fait le point sur les id\u00e9es re\u00e7ues concernant ce dispositif m\u00e9dical. La pose d&rsquo;un implant dentaire est douloureuse FAUX. La pose d\u2019un\u00a0implant dentaire, lorsqu\u2019elle est bien men\u00e9e, entraine moins&hellip;<\/p>\n","protected":false},"author":2,"featured_media":912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/posts\/911"}],"collection":[{"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/comments?post=911"}],"version-history":[{"count":1,"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/posts\/911\/revisions"}],"predecessor-version":[{"id":913,"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/posts\/911\/revisions\/913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/media\/912"}],"wp:attachment":[{"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/media?parent=911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/categories?post=911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/implantologie-rabat.com\/index.php\/wp-json\/wp\/v2\/tags?post=911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}